{"id":1007,"date":"2014-11-05T18:52:02","date_gmt":"2014-11-05T18:52:02","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=1007"},"modified":"2014-11-05T19:00:26","modified_gmt":"2014-11-05T19:00:26","slug":"encontro-vocacional-na-comunidade-da-aurora-sao-luis-ma","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/encontro-vocacional-na-comunidade-da-aurora-sao-luis-ma\/","title":{"rendered":"Encontro Vocacional na Comunidade da Aurora, S\u00e3o Lu\u00eds &#8211; MA"},"content":{"rendered":"<p>No \u00faltimo dia 02\/11 aconteceu mais um encontro vocacional na comunidade da Aurora em S\u00e3o Lu\u00eds.<\/p>\n<p>Participaram meninas de v\u00e1rias comunidades.<\/p>\n<p>Iniciamos o dia participando da Missa no Carmelo. Ap\u00f3s o caf\u00e9 da manh\u00e3 iniciamos nossas reflex\u00f5es sobre a santidade, tendo como ponto de partida o exemplo do nosso Pai Fundador que, no dia 01\/11 celebraria seu nascimento. Lembramos tamb\u00e9m dos nossos parentes, amigos e conhecidos que j\u00e1 partiram desta vida.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/1800222_1501727656771472_2694569899253352161_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-1008 \" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/1800222_1501727656771472_2694569899253352161_n.jpg?resize=633%2C475\" alt=\"1800222_1501727656771472_2694569899253352161_n\" width=\"633\" height=\"475\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/1800222_1501727656771472_2694569899253352161_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/1800222_1501727656771472_2694569899253352161_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 633px) 100vw, 633px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10606287_1501730836771154_4768195876256333499_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-1009 \" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10606287_1501730836771154_4768195876256333499_n.jpg?resize=688%2C516\" alt=\"10606287_1501730836771154_4768195876256333499_n\" width=\"688\" height=\"516\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10606287_1501730836771154_4768195876256333499_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10606287_1501730836771154_4768195876256333499_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 688px) 100vw, 688px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/544930_1501729366771301_773817211220183102_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-1010 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/544930_1501729366771301_773817211220183102_n.jpg?resize=687%2C515\" alt=\"544930_1501729366771301_773817211220183102_n\" width=\"687\" height=\"515\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/544930_1501729366771301_773817211220183102_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/544930_1501729366771301_773817211220183102_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 687px) 100vw, 687px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10801674_1501729073437997_8494068594740078102_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1011 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10801674_1501729073437997_8494068594740078102_n.jpg?resize=687%2C515\" alt=\"10801674_1501729073437997_8494068594740078102_n\" width=\"687\" height=\"515\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10801674_1501729073437997_8494068594740078102_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10801674_1501729073437997_8494068594740078102_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 687px) 100vw, 687px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10696444_1501731440104427_8788443491516610602_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-1012 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10696444_1501731440104427_8788443491516610602_n.jpg?resize=695%2C521\" alt=\"10696444_1501731440104427_8788443491516610602_n\" width=\"695\" height=\"521\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10696444_1501731440104427_8788443491516610602_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10696444_1501731440104427_8788443491516610602_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 695px) 100vw, 695px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10690283_1501728116771426_6218679794846986515_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-1013 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10690283_1501728116771426_6218679794846986515_n.jpg?resize=698%2C523\" alt=\"10690283_1501728116771426_6218679794846986515_n\" width=\"698\" height=\"523\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10690283_1501728116771426_6218679794846986515_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10690283_1501728116771426_6218679794846986515_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10424980_559825754163007_5746346657516231396_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-1014 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10424980_559825754163007_5746346657516231396_n.jpg?resize=459%2C612\" alt=\"10424980_559825754163007_5746346657516231396_n\" width=\"459\" height=\"612\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10424980_559825754163007_5746346657516231396_n.jpg?w=480 480w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10424980_559825754163007_5746346657516231396_n.jpg?resize=225%2C300 225w\" sizes=\"(max-width: 459px) 100vw, 459px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10678622_1501728433438061_5788006437447382047_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1015 aligncenter\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10678622_1501728433438061_5788006437447382047_n.jpg?resize=695%2C521\" alt=\"10678622_1501728433438061_5788006437447382047_n\" width=\"695\" height=\"521\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10678622_1501728433438061_5788006437447382047_n.jpg?w=960 960w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2014\/11\/10678622_1501728433438061_5788006437447382047_n.jpg?resize=300%2C225 300w\" sizes=\"(max-width: 695px) 100vw, 695px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo dia 02\/11 aconteceu mais um encontro vocacional na comunidade da Aurora em S\u00e3o Lu\u00eds. Participaram meninas de v\u00e1rias comunidades. Iniciamos o dia participando da Missa no Carmelo. Ap\u00f3s o caf\u00e9 da manh\u00e3 iniciamos nossas reflex\u00f5es sobre a santidade, tendo como ponto de partida o exemplo do nosso Pai Fundador que, no dia 01\/11 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-gf","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1007"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=1007"}],"version-history":[{"count":6,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1007\/revisions"}],"predecessor-version":[{"id":1021,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1007\/revisions\/1021"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=1007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=1007"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=1007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}