{"id":1309,"date":"2015-07-04T11:00:37","date_gmt":"2015-07-04T11:00:37","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=1309"},"modified":"2015-07-04T02:05:42","modified_gmt":"2015-07-04T02:05:42","slug":"triduo-a-sao-sigismundo-em-sao-luis-ma","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/triduo-a-sao-sigismundo-em-sao-luis-ma\/","title":{"rendered":"Tr\u00edduo a S\u00e3o Sigismundo em S\u00e3o Lu\u00eds, MA"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<span style=\"color: #000000;\">Unidas com toda a Congrega\u00e7\u00e3o celebramos solenemente a festa do Pai Fundador. A festa foi preparada atrav\u00e9s de um tr\u00edduo, realizado na igreja matriz, antes da Missa da noite.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A Eucaristia do dia 26 de junho foi presidia pelo p\u00e1roco frei Jos\u00e9 de Arimat\u00e9ia da Luz Ara\u00fajo e pelo frei Benedito das Chagas de Carvalho. Na homilia o P\u00e1roco sublinhou o chamado de Sigismundo \u00e0 santidade, a partir de seu nascimento, no dia da solenidade de todos os Santos. A resposta que deu foi atrav\u00e9s da f\u00e9 que agiu incessantemente pela caridade. Depois da homilia mais sete pessoas foram admitidas ao <strong>Grupo de Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Ao final da celebra\u00e7\u00e3o, frei Arimat\u00e9ia deu a b\u00ean\u00e7\u00e3o individual, com a rel\u00edquia de S\u00e3o Sigismundo, a cada um dos participantes da missa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 A celebra\u00e7\u00e3o foi animada pelos seminaristas da diocese de Imperatriz, MA.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">\n<div id=\"slideshow-1315-6a04e49745f1b\" class=\"wk-slideshow wk-slideshow-default\" data-widgetkit=\"slideshow\" data-options='{\"style\":\"default\",\"autoplay\":1,\"interval\":5000,\"width\":1000,\"height\":380,\"duration\":500,\"index\":0,\"order\":\"default\",\"navigation\":0,\"buttons\":1,\"slices\":20,\"animated\":\"scale\",\"caption_animation_duration\":500}'>\n\t<div>\n\t\t<ul class=\"slides\">\n\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-4-e1435972508705.jpg\"><img src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-4-e1435972508705.jpg?resize=700%2C525\" alt=\"FSSG (4)\" width=\"700\" height=\"525\" class=\" size-full wp-image-1288 aligncenter\" data-recalc-dims=\"1\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-18-e1435972539427.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-18-e1435972539427.jpg\" alt=\"FSSG 18\" width=\"700\" height=\"717\" class=\" size-full wp-image-1290 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-19-e1435972557453.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-19-e1435972557453.jpg\" alt=\"FSSG 19\" width=\"700\" height=\"638\" class=\" size-full wp-image-1291 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-26-e1435972592362.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-26-e1435972592362.jpg\" alt=\"FSSG 26\" width=\"700\" height=\"525\" class=\" size-full wp-image-1293 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-35-e1435972621118.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-35-e1435972621118.jpg\" alt=\"FSSG 35\" width=\"700\" height=\"682\" class=\" size-full wp-image-1295 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-37-e1435972636691.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-37-e1435972636691.jpg\" alt=\"FSSG 37\" width=\"700\" height=\"525\" class=\" size-full wp-image-1296 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-51-e1435972666260.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-51-e1435972666260.jpg\" alt=\"FSSG 51\" width=\"700\" height=\"525\" class=\" size-full wp-image-1298 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-21-e1435972577376.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-21-e1435972577376.jpg\" alt=\"\" width=\"700\" height=\"1152\" class=\" size-full wp-image-1292 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-48-e1435972652317.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-48-e1435972652317.jpg\" alt=\"FSSG 48\" width=\"700\" height=\"668\" class=\" size-full wp-image-1297 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><p><a href=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-15-e1435972525517.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2015\/07\/FSSG-15-e1435972525517.jpg\" alt=\"FSSG (15)\" width=\"700\" height=\"525\" class=\" size-full wp-image-1289 aligncenter\" \/><\/a><\/p><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t<div class=\"next\"><\/div><div class=\"prev\"><\/div>\t\t<div class=\"caption\"><\/div><ul class=\"captions\"><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><\/ul>\n\t<\/div>\n\t<\/div><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Unidas com toda a Congrega\u00e7\u00e3o celebramos solenemente a festa do Pai Fundador. A festa foi preparada atrav\u00e9s de um tr\u00edduo, realizado na igreja matriz, antes da Missa da noite. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A Eucaristia do dia 26 de junho foi presidia pelo p\u00e1roco frei Jos\u00e9 de Arimat\u00e9ia da Luz Ara\u00fajo e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-l7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1309"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=1309"}],"version-history":[{"count":6,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1309\/revisions"}],"predecessor-version":[{"id":1316,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/1309\/revisions\/1316"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=1309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=1309"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=1309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}