{"id":6073,"date":"2018-08-17T14:04:58","date_gmt":"2018-08-17T17:04:58","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=6073"},"modified":"2018-10-17T14:39:18","modified_gmt":"2018-10-17T17:39:18","slug":"6073-2","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/6073-2\/","title":{"rendered":"Retiro do grupo de Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 \u2013 Ilha do Governador \u2013 Rio de Janeiro"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No dia <strong>29 de julho de 2018<\/strong> , aconteceu o retiro anual\u00a0 do <strong>Grupo de Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 da Comunidade das Irm\u00e3s do Rio de Janeiro, na Capela Santa Rita da Par\u00f3quia S\u00e3o Sebasti\u00e3o, na Ilha do Governador.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Neste ano a Igreja destaca os crist\u00e3os leigos, optamos rezar e trabalhar o tema Sal da ter\u00e1 e Luz do mundo, \u201colhando o exemplo de S\u00e3o Jos\u00e9, como ele todos s\u00e3o chamados a ser Sal e Luz\u201d, em tudo aquilo que Deus confia a cada um. Iniciamos o dia com uma din\u00e2mica de acolhida e anima\u00e7\u00e3o, conduzido pela ir. Rosenilda e Cristina que acompanhou o dia todo com os cantos. Seguida com a ora\u00e7\u00e3o inicial conduzida pela Sheila paroquiana e membro do GOSJ, na qual refletimos o texto de Mt\u00a0 5,13-14. Dando continuidade com uma din\u00e2mica dirigido por Telma, onde refletiu-a import\u00e2ncia de Sal e Luz na vida do outro.\u00a0 Tivemos<strong> adora\u00e7\u00e3o ao Sant\u00edssimo Sacramento <\/strong>na qual rezamos por novas voca\u00e7\u00f5es, e pelos membros do\u00a0 GOSJ conduzido pela ir. Rosenilda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A tarde teve a presen\u00e7a do pe. Walmir da Silva , Capel\u00e3o da Marinha, ministrando uma palestra sobre o tema proposto, com base no Evangelho segundo Mt 5,13-14, dando \u00eanfase na import\u00e2ncia do leigo crist\u00e3o na miss\u00e3o da Igreja e da Sociedade, fazendo um paralelo com a\u00a0 pessoa de S\u00e3o Jos\u00e9: destacando tr\u00eas pontos : Ser presen\u00e7a \/ palavra dita \/ afeto. Tamb\u00e9m presidiu a Santa Missa.<\/span><\/p>\n<p style=\"text-align: center;\">\n<div id=\"slideset-6093-6a04eea438532\" class=\"wk-slideset wk-slideset-default\" data-widgetkit=\"slideset\" data-options='{\"style\":\"default\",\"width\":\"auto\",\"height\":\"auto\",\"effect\":\"slide\",\"index\":0,\"autoplay\":1,\"interval\":5000,\"items_per_set\":1,\"navigation\":1,\"buttons\":1,\"title\":0,\"duration\":300}'>\n\t<div>\n\t\t<div class=\"sets\">\n\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide1.jpg?resize=680%2C453\" alt=\"Slide1\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6078\" data-recalc-dims=\"1\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide2.jpg\" alt=\"Slide2\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6079\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide3.jpg\" alt=\"Slide3\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6080\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide4.jpg\" alt=\"Slide4\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6081\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide5.jpg\" alt=\"Slide5\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6082\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide6.jpg\" alt=\"Slide6\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6083\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide7.jpg\" alt=\"Slide7\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6084\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide8.jpg\" alt=\"Slide8\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6085\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide9.jpg\" alt=\"Slide9\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6086\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide10.jpg\" alt=\"Slide10\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6087\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide11.jpg\" alt=\"Slide11\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6088\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide12.jpg\" alt=\"Slide12\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6089\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide13.jpg\" alt=\"Slide13\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6090\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"set\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<article class=\"wk-content\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2018\/10\/Slide14.jpg\" alt=\"Slide14\" width=\"680\" height=\"453\" class=\"aligncenter size-full wp-image-6091\" \/><\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"next\"><\/div><div class=\"prev\"><\/div>\t<\/div>\n\t\t<ul class=\"nav icon\"><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><\/ul>\n\t<\/div><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tivemos momento de partilha e testemunho de varias pessoas. A ir. Dobroslawa apresentou slides com fotos dos retiros anteriores. Segundo a partilha dos participantes foi um retiro que renovou a confian\u00e7a e a f\u00e9, segundo eles voltam para a casa mais devotos de S\u00e3o Jos\u00e9 e mais corajosos para continuar na miss\u00e3o. Teve a participa\u00e7\u00e3o de 26 pessoas, junto com ir. Arkadia e postulante Gabriele que ajudaram na prepara\u00e7\u00e3o e organiza\u00e7\u00e3o do retiro. Louvado seja Deus pelas gra\u00e7as alcan\u00e7adas!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 29 de julho de 2018 , aconteceu o retiro anual\u00a0 do Grupo de Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 da Comunidade das Irm\u00e3s do Rio de Janeiro, na Capela Santa Rita da Par\u00f3quia S\u00e3o Sebasti\u00e3o, na Ilha do Governador. Neste ano a Igreja destaca os crist\u00e3os leigos, optamos rezar e trabalhar o tema Sal da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[57,117,52,69],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-1zX","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6073"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=6073"}],"version-history":[{"count":3,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6073\/revisions"}],"predecessor-version":[{"id":6094,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6073\/revisions\/6094"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=6073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=6073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=6073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}