{"id":6403,"date":"2019-04-03T22:11:28","date_gmt":"2019-04-04T01:11:28","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=6403"},"modified":"2019-04-03T22:11:28","modified_gmt":"2019-04-04T01:11:28","slug":"formacao-na-comunidade-nossa-senhora-aparecida-em-moncao-ma","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/formacao-na-comunidade-nossa-senhora-aparecida-em-moncao-ma\/","title":{"rendered":"Forma\u00e7\u00e3o na Comunidade Nossa Senhora Aparecida, em Mon\u00e7\u00e3o, MA"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No dia 31 de mar\u00e7o, na comunidade <strong>Nossa Senhora Aparecida<\/strong>, realizou-se a primeira iniciativa da <strong>assembl\u00e9ia paroquial<\/strong> realizada nos dias 22 a 24 de fevereiro, para o setor um (sendo oito setores) da par\u00f3quia S\u00e3o Francisco Xavier: a forma\u00e7\u00e3o teve como tema a <strong>pastoral catequ\u00e9tica<\/strong> e a <strong>pastoral do batismo<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Ir. Beyzyma<\/strong> abriu o <strong>encontro formativo<\/strong> com uma riqu\u00edssima introdu\u00e7\u00e3o sobre o significado e import\u00e2ncia destas duas pastorais na Igreja, bem como para cada <strong>Crist\u00e3o<\/strong>. Introduziu os catequistas no caminho crist\u00e3o, levando-os a perceberem os recursos e meios que o pr\u00f3prio <strong>Cristo<\/strong>, que \u00e9 o <strong>centro<\/strong> de toda a caminhada crist\u00e3, deixou na sua Igreja, para que cada crist\u00e3o conseguisse chegar \u00e0s alegrias do c\u00e9u. Assim, Ir. Beyzyma com sua sabedoria e experi\u00eancia, abriu espa\u00e7o para o desenvolvimento da forma\u00e7\u00e3o, que foi conduzida pelos coordenadores das pastorais do batismo, <strong>Jos\u00e9 Reinaldo<\/strong>, e da catequese, com <strong>Daniele Marques<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A forma\u00e7\u00e3o deu frutos imediatos: a implanta\u00e7\u00e3o da pastoral do batismo nas comunidades; Nossa Senhora Aparecida, Nossa Senhora de F\u00e1tima e S\u00e3o Jos\u00e9. A ressurrei\u00e7\u00e3o da catequese na comunidade Nossa Senhora Aparecida e a a\u00e7\u00e3o de encontros mensais de forma\u00e7\u00e3o sobre o batismo, para pais dos catequizandos, em todas as comunidades.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O encontro teve seu fim e \u00e1pice, \u00e0s 16h, com a celebra\u00e7\u00e3o da <strong>Santa Missa,<\/strong> presidida pelo <strong>p\u00e1roco, Frei Francisco Valadares.<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">\n<div id=\"slideshow-6402-6a04ea794c9f9\" class=\"wk-slideshow wk-slideshow-default\" data-widgetkit=\"slideshow\" data-options='{\"style\":\"default\",\"autoplay\":1,\"interval\":5000,\"width\":1000,\"height\":380,\"duration\":500,\"index\":0,\"order\":\"default\",\"navigation\":1,\"buttons\":0,\"slices\":20,\"animated\":\"scale\",\"caption_animation_duration\":500}'>\n\t<div>\n\t\t<ul class=\"slides\">\n\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide1-1.png?resize=654%2C489\" alt=\"Slide1\" width=\"654\" height=\"489\" class=\"aligncenter size-full wp-image-6392\" data-recalc-dims=\"1\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide2-1.png\" alt=\"Slide2\" width=\"369\" height=\"490\" class=\"aligncenter size-full wp-image-6393\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide3-1.png\" alt=\"Slide3\" width=\"655\" height=\"487\" class=\"aligncenter size-full wp-image-6394\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide4-1.png\" alt=\"Slide4\" width=\"652\" height=\"490\" class=\"aligncenter size-full wp-image-6395\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide5-1.png\" alt=\"Slide5\" width=\"370\" height=\"490\" class=\"aligncenter size-full wp-image-6396\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide6-1.png\" alt=\"Slide6\" width=\"366\" height=\"490\" class=\"aligncenter size-full wp-image-6397\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide7-1.png\" alt=\"Slide7\" width=\"369\" height=\"489\" class=\"aligncenter size-full wp-image-6398\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide8-1.png\" alt=\"Slide8\" width=\"655\" height=\"488\" class=\"aligncenter size-full wp-image-6399\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide9-1.png\" alt=\"Slide9\" width=\"656\" height=\"491\" class=\"aligncenter size-full wp-image-6400\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/04\/Slide10-1.png\" alt=\"Slide10\" width=\"655\" height=\"491\" class=\"aligncenter size-full wp-image-6401\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<div class=\"caption\"><\/div><ul class=\"captions\"><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><\/ul>\n\t<\/div>\n\t<ul class=\"nav\"><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><\/ul><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 31 de mar\u00e7o, na comunidade Nossa Senhora Aparecida, realizou-se a primeira iniciativa da assembl\u00e9ia paroquial realizada nos dias 22 a 24 de fevereiro, para o setor um (sendo oito setores) da par\u00f3quia S\u00e3o Francisco Xavier: a forma\u00e7\u00e3o teve como tema a pastoral catequ\u00e9tica e a pastoral do batismo. Ir. Beyzyma abriu o encontro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[61,70,251,252,254,253],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-1Fh","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6403"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=6403"}],"version-history":[{"count":1,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6403\/revisions"}],"predecessor-version":[{"id":6404,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6403\/revisions\/6404"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=6403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=6403"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=6403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}