{"id":6415,"date":"2019-05-10T10:10:16","date_gmt":"2019-05-10T13:10:16","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=6415"},"modified":"2019-05-10T10:10:16","modified_gmt":"2019-05-10T13:10:16","slug":"encontro-das-irmas-junioristas-2","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/encontro-das-irmas-junioristas-2\/","title":{"rendered":"Encontro das Irm\u00e3s Junioristas!"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0 \u00a0 \u00a0 \u00a0 Nos dias 02 a 04 de maio de 2019, foi realizado o encontro das <strong>Irm\u00e3s Junioristas,\u00a0<\/strong>da Congrega\u00e7\u00e3o das Irm\u00e3s de S\u00e3o Jos\u00e9,\u00a0na comunidade da Barra do Corda, MA. O assessor do encontro foi o <strong>Frei Jos\u00e9 Nilton Leandro da Costa, OFMCap,\u00a0<\/strong>que ajudou as Irm\u00e3s a aprofundar o tema: <strong>&#8220;Vida Consagrada &#8211; plenitude da vida de f\u00e9&#8221;.\u00a0<\/strong>A cada dia o encontro foi iniciado com a ora\u00e7\u00e3o da Santa Missa e, al\u00e9m das confer\u00eancias, as Irm\u00e3s estiveram unidas em <strong>adora\u00e7\u00e3o ao<\/strong> <strong>Sant\u00edssimo Sacramento<\/strong>, junto \u00e0 comunidade das Irm\u00e3s da Barra do Corda.<\/span><\/p>\n<p style=\"text-align: center;\">\n<div id=\"slideshow-6424-6a04eadcd9949\" class=\"wk-slideshow wk-slideshow-default\" data-widgetkit=\"slideshow\" data-options='{\"style\":\"default\",\"autoplay\":1,\"interval\":5000,\"width\":1000,\"height\":380,\"duration\":500,\"index\":0,\"order\":\"default\",\"navigation\":1,\"buttons\":1,\"slices\":20,\"animated\":\"scroll\",\"caption_animation_duration\":500}'>\n\t<div>\n\t\t<ul class=\"slides\">\n\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide7.png?resize=652%2C491\" alt=\"Slide7\" width=\"652\" height=\"491\" class=\"aligncenter size-full wp-image-6423\" data-recalc-dims=\"1\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide6.png\" alt=\"Slide6\" width=\"655\" height=\"489\" class=\"aligncenter size-full wp-image-6422\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide3.png\" alt=\"Slide3\" width=\"654\" height=\"490\" class=\"aligncenter size-full wp-image-6419\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide5.png\" alt=\"Slide5\" width=\"653\" height=\"489\" class=\"aligncenter size-full wp-image-6421\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide4.png\" alt=\"Slide4\" width=\"655\" height=\"489\" class=\"aligncenter size-full wp-image-6420\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide2.png\" alt=\"Slide2\" width=\"654\" height=\"487\" class=\"aligncenter size-full wp-image-6418\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t<article class=\"wk-content clearfix\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAJEAAAAAAP\/\/\/\/\/\/\/wAAACH5BAEHAAIALAAAAAABAAEAAAICVAEAOw==\" data-src=\"http:\/\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2019\/05\/Slide1.png\" alt=\"Slide1\" width=\"655\" height=\"490\" class=\"aligncenter size-full wp-image-6417\" \/><\/article>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t<div class=\"next\"><\/div><div class=\"prev\"><\/div>\t\t<div class=\"caption\"><\/div><ul class=\"captions\"><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><li><\/li><\/ul>\n\t<\/div>\n\t<ul class=\"nav\"><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><\/ul><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 Nos dias 02 a 04 de maio de 2019, foi realizado o encontro das Irm\u00e3s Junioristas,\u00a0da Congrega\u00e7\u00e3o das Irm\u00e3s de S\u00e3o Jos\u00e9,\u00a0na comunidade da Barra do Corda, MA. O assessor do encontro foi o Frei Jos\u00e9 Nilton Leandro da Costa, OFMCap,\u00a0que ajudou as Irm\u00e3s a aprofundar o tema: &#8220;Vida Consagrada &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-1Ft","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6415"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=6415"}],"version-history":[{"count":4,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6415\/revisions"}],"predecessor-version":[{"id":6427,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/6415\/revisions\/6427"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=6415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=6415"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=6415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}