{"id":7792,"date":"2022-06-30T14:01:15","date_gmt":"2022-06-30T17:01:15","guid":{"rendered":"http:\/\/irmasdesaojose.com.br\/portal\/?p=7792"},"modified":"2023-08-24T16:29:03","modified_gmt":"2023-08-24T19:29:03","slug":"chamados-a-santidade-este-foi-o-tema-da-tarde-josefina","status":"publish","type":"post","link":"http:\/\/irmasdesaojose.com.br\/portal\/chamados-a-santidade-este-foi-o-tema-da-tarde-josefina\/","title":{"rendered":"Chamados \u00e0 santidade &#8211; este foi o tema da Tarde Josefina"},"content":{"rendered":"<div class=\"yahoo-style-wrap\">\n<div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">Neste domingo, 26.06.2022, os membros do <strong>Grupo de\u00a0 Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 de Curitiba<\/strong> participaram da tarde de encontro por ocasi\u00e3o da Festa de S\u00e3o Sigismundo Gorazdowski, Fundador da Congrega\u00e7\u00e3o. O tema da tarde foi: <em><strong>&#8220;Chamados \u00e0 SANTIDADE&#8221;.\u00a0\u00a0<\/strong><\/em><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Pe. Ednilson de Jesus Dantas da Silva<\/em>, MIC conduziu a reflex\u00e3o sobre o tema apresentando a pessoa de S\u00e3o Pedro e seu caminho para a santidade, que a pr\u00f3pria Palavra de Deus apresenta nas suas p\u00e1ginas.\u00a0 O Padre tra\u00e7ou um caminho de 10 atitudes na vida de Pedro que permitiram a ele tornar-se santo.\u00a0 Assim como Pedro e tamb\u00e9m como o padre Sigismundo passaram por este caminho, cada um de n\u00f3s \u00e9 convidado a:<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">1. Conhecer Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">2. Sofrer por Jesus ou com Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">3. Obedecer a Palavra de Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">4. Vencer com Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">5. Permanecer com Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">6. Defender Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">7. Perdoar como Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">8. Valorizar Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">9. Confiar em Jesus;<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">10. Amar como Jesus;<\/span><\/div>\n<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">Enriquecidos com a reflex\u00e3o participamos na Eucaristia onde mais uma vez Deus falou pela sua Palavra e nos uniu na mesa eucar\u00edstica fortalecendo em n\u00f3s o desejo de santidade.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">Ap\u00f3s, tivemos um momento de confraterniza\u00e7\u00e3o e Adora\u00e7\u00e3o ao Sant\u00edssimo Sacramento onde pudemos juntos agradecer pela vida, miss\u00e3o e carisma do Pai Fundador, realizado at\u00e9 hoje pela Congrega\u00e7\u00e3o. Na Adora\u00e7\u00e3o ao Sant\u00edssimo Sacramento entregamos a Deus ora\u00e7\u00f5es de gratid\u00e3o e de s\u00faplica\u00a0 agradecendo a Ele de modo especial pelo exemplo de vida e santidade de S\u00e3o Sigismundo.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">Essa tarde foi muito especial e fortaleceu mais uma vez os la\u00e7os entre os membros dando a eles a oportunidade do encontro com Deus e com o pr\u00f3ximo.\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">O Grupo de ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 ir\u00e1 continuar seus encontros e participa\u00e7\u00e3o semanal da <strong>Santa Missa, nas quartas-feiras.<\/strong><\/span><\/div>\n<\/div>\n<\/div>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7813\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide1.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7813\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide1.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide1.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide2.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7815\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide2.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7815\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide2.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide2.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide3.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7814\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide3.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7814\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide3.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide3.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide4.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7818\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide4.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7818\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide4.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide4.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide5.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7819\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide5.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7819\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide5.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide5.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide6.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"682\" height=\"491\" data-id=\"7820\" src=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide6.jpg?resize=682%2C491\" alt=\"\" class=\"wp-image-7820\" srcset=\"https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide6.jpg?w=682 682w, https:\/\/i0.wp.com\/irmasdesaojose.com.br\/portal\/wp-content\/uploads\/2022\/11\/Slide6.jpg?resize=300%2C216 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, 26.06.2022, os membros do Grupo de\u00a0 Ora\u00e7\u00e3o de S\u00e3o Jos\u00e9 de Curitiba participaram da tarde de encontro por ocasi\u00e3o da Festa de S\u00e3o Sigismundo Gorazdowski, Fundador da Congrega\u00e7\u00e3o. O tema da tarde foi: &#8220;Chamados \u00e0 SANTIDADE&#8221;.\u00a0\u00a0 Pe. Ednilson de Jesus Dantas da Silva, MIC conduziu a reflex\u00e3o sobre o tema apresentando a pessoa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[17,32,52,137],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4Ftkv-21G","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/7792"}],"collection":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/comments?post=7792"}],"version-history":[{"count":4,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/7792\/revisions"}],"predecessor-version":[{"id":7959,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/posts\/7792\/revisions\/7959"}],"wp:attachment":[{"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/media?parent=7792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/categories?post=7792"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/irmasdesaojose.com.br\/portal\/wp-json\/wp\/v2\/tags?post=7792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}